{"id":2797,"date":"2026-07-22T14:34:55","date_gmt":"2026-07-22T12:34:55","guid":{"rendered":"https:\/\/www.zabler.de\/sortiment\/mini-rotelle-500g\/"},"modified":"2026-07-22T14:35:26","modified_gmt":"2026-07-22T12:35:26","slug":"mini-rotelle-500g","status":"publish","type":"sortiment","link":"https:\/\/www.zabler.de\/en\/sortiment\/mini-rotelle-500g\/","title":{"rendered":"Mini-Rotelle"},"featured_media":2795,"template":"","meta":{"_acf_changed":false},"kategorie":[29],"class_list":["post-2797","sortiment","type-sortiment","status-publish","has-post-thumbnail","hentry","kategorie-paradiso-bio-500-g"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mini-Rotelle &#8211; Zabler.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zabler.de\/en\/sortiment\/mini-rotelle-500g\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mini-Rotelle &#8211; Zabler.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zabler.de\/en\/sortiment\/mini-rotelle-500g\/\" \/>\n<meta property=\"og:site_name\" content=\"Zabler.de\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-22T12:35:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zabler.de\/wp-content\/uploads\/2026\/07\/Paradiso-Bio-Mini-Rotelle-500g.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"429\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/mini-rotelle-500g\\\/\",\"url\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/mini-rotelle-500g\\\/\",\"name\":\"Mini-Rotelle &#8211; Zabler.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/mini-rotelle-500g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/mini-rotelle-500g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zabler.de\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Paradiso-Bio-Mini-Rotelle-500g.webp\",\"datePublished\":\"2026-07-22T12:34:55+00:00\",\"dateModified\":\"2026-07-22T12:35:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/mini-rotelle-500g\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/mini-rotelle-500g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/mini-rotelle-500g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zabler.de\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Paradiso-Bio-Mini-Rotelle-500g.webp\",\"contentUrl\":\"https:\\\/\\\/www.zabler.de\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Paradiso-Bio-Mini-Rotelle-500g.webp\",\"width\":429,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/mini-rotelle-500g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mini-Rotelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/\",\"name\":\"Zabler.de\",\"description\":\"Entdecken Sie unsere Zabler Klassiker\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mini-Rotelle &#8211; Zabler.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zabler.de\/en\/sortiment\/mini-rotelle-500g\/","og_locale":"en_US","og_type":"article","og_title":"Mini-Rotelle &#8211; Zabler.de","og_url":"https:\/\/www.zabler.de\/en\/sortiment\/mini-rotelle-500g\/","og_site_name":"Zabler.de","article_modified_time":"2026-07-22T12:35:26+00:00","og_image":[{"width":429,"height":1000,"url":"https:\/\/www.zabler.de\/wp-content\/uploads\/2026\/07\/Paradiso-Bio-Mini-Rotelle-500g.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zabler.de\/en\/sortiment\/mini-rotelle-500g\/","url":"https:\/\/www.zabler.de\/en\/sortiment\/mini-rotelle-500g\/","name":"Mini-Rotelle &#8211; Zabler.de","isPartOf":{"@id":"https:\/\/www.zabler.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zabler.de\/en\/sortiment\/mini-rotelle-500g\/#primaryimage"},"image":{"@id":"https:\/\/www.zabler.de\/en\/sortiment\/mini-rotelle-500g\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zabler.de\/wp-content\/uploads\/2026\/07\/Paradiso-Bio-Mini-Rotelle-500g.webp","datePublished":"2026-07-22T12:34:55+00:00","dateModified":"2026-07-22T12:35:26+00:00","breadcrumb":{"@id":"https:\/\/www.zabler.de\/en\/sortiment\/mini-rotelle-500g\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zabler.de\/en\/sortiment\/mini-rotelle-500g\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zabler.de\/en\/sortiment\/mini-rotelle-500g\/#primaryimage","url":"https:\/\/www.zabler.de\/wp-content\/uploads\/2026\/07\/Paradiso-Bio-Mini-Rotelle-500g.webp","contentUrl":"https:\/\/www.zabler.de\/wp-content\/uploads\/2026\/07\/Paradiso-Bio-Mini-Rotelle-500g.webp","width":429,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.zabler.de\/en\/sortiment\/mini-rotelle-500g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.zabler.de\/en\/"},{"@type":"ListItem","position":2,"name":"Mini-Rotelle"}]},{"@type":"WebSite","@id":"https:\/\/www.zabler.de\/en\/#website","url":"https:\/\/www.zabler.de\/en\/","name":"Zabler.de","description":"Entdecken Sie unsere Zabler Klassiker","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zabler.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/sortiment\/2797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/sortiment"}],"about":[{"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/types\/sortiment"}],"version-history":[{"count":1,"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/sortiment\/2797\/revisions"}],"predecessor-version":[{"id":2798,"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/sortiment\/2797\/revisions\/2798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/media\/2795"}],"wp:attachment":[{"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/media?parent=2797"}],"wp:term":[{"taxonomy":"kategorie","embeddable":true,"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/kategorie?post=2797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}