{"id":2735,"date":"2026-07-22T14:10:19","date_gmt":"2026-07-22T12:10:19","guid":{"rendered":"https:\/\/www.zabler.de\/sortiment\/spirelli-1000g\/"},"modified":"2026-07-22T14:10:42","modified_gmt":"2026-07-22T12:10:42","slug":"spirelli-1000g","status":"publish","type":"sortiment","link":"https:\/\/www.zabler.de\/en\/sortiment\/spirelli-1000g\/","title":{"rendered":"Spirelli"},"featured_media":2733,"template":"","meta":{"_acf_changed":false},"kategorie":[36],"class_list":["post-2735","sortiment","type-sortiment","status-publish","has-post-thumbnail","hentry","kategorie-hochzeit-nudeln-1000-g-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spirelli &#8211; Zabler.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zabler.de\/en\/sortiment\/spirelli-1000g\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spirelli &#8211; Zabler.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zabler.de\/en\/sortiment\/spirelli-1000g\/\" \/>\n<meta property=\"og:site_name\" content=\"Zabler.de\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-22T12:10:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zabler.de\/wp-content\/uploads\/2026\/07\/Hochzeit-Nudeln-Spirelli-1000g.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"501\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/spirelli-1000g\\\/\",\"url\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/spirelli-1000g\\\/\",\"name\":\"Spirelli &#8211; Zabler.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/spirelli-1000g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/spirelli-1000g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zabler.de\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Hochzeit-Nudeln-Spirelli-1000g.webp\",\"datePublished\":\"2026-07-22T12:10:19+00:00\",\"dateModified\":\"2026-07-22T12:10:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/spirelli-1000g\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/spirelli-1000g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/spirelli-1000g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zabler.de\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Hochzeit-Nudeln-Spirelli-1000g.webp\",\"contentUrl\":\"https:\\\/\\\/www.zabler.de\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Hochzeit-Nudeln-Spirelli-1000g.webp\",\"width\":501,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/sortiment\\\/spirelli-1000g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spirelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/\",\"name\":\"Zabler.de\",\"description\":\"Entdecken Sie unsere Zabler Klassiker\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zabler.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spirelli &#8211; Zabler.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zabler.de\/en\/sortiment\/spirelli-1000g\/","og_locale":"en_US","og_type":"article","og_title":"Spirelli &#8211; Zabler.de","og_url":"https:\/\/www.zabler.de\/en\/sortiment\/spirelli-1000g\/","og_site_name":"Zabler.de","article_modified_time":"2026-07-22T12:10:42+00:00","og_image":[{"width":501,"height":1000,"url":"https:\/\/www.zabler.de\/wp-content\/uploads\/2026\/07\/Hochzeit-Nudeln-Spirelli-1000g.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zabler.de\/en\/sortiment\/spirelli-1000g\/","url":"https:\/\/www.zabler.de\/en\/sortiment\/spirelli-1000g\/","name":"Spirelli &#8211; Zabler.de","isPartOf":{"@id":"https:\/\/www.zabler.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zabler.de\/en\/sortiment\/spirelli-1000g\/#primaryimage"},"image":{"@id":"https:\/\/www.zabler.de\/en\/sortiment\/spirelli-1000g\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zabler.de\/wp-content\/uploads\/2026\/07\/Hochzeit-Nudeln-Spirelli-1000g.webp","datePublished":"2026-07-22T12:10:19+00:00","dateModified":"2026-07-22T12:10:42+00:00","breadcrumb":{"@id":"https:\/\/www.zabler.de\/en\/sortiment\/spirelli-1000g\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zabler.de\/en\/sortiment\/spirelli-1000g\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zabler.de\/en\/sortiment\/spirelli-1000g\/#primaryimage","url":"https:\/\/www.zabler.de\/wp-content\/uploads\/2026\/07\/Hochzeit-Nudeln-Spirelli-1000g.webp","contentUrl":"https:\/\/www.zabler.de\/wp-content\/uploads\/2026\/07\/Hochzeit-Nudeln-Spirelli-1000g.webp","width":501,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.zabler.de\/en\/sortiment\/spirelli-1000g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.zabler.de\/en\/"},{"@type":"ListItem","position":2,"name":"Spirelli"}]},{"@type":"WebSite","@id":"https:\/\/www.zabler.de\/en\/#website","url":"https:\/\/www.zabler.de\/en\/","name":"Zabler.de","description":"Entdecken Sie unsere Zabler Klassiker","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zabler.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/sortiment\/2735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/sortiment"}],"about":[{"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/types\/sortiment"}],"version-history":[{"count":1,"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/sortiment\/2735\/revisions"}],"predecessor-version":[{"id":2736,"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/sortiment\/2735\/revisions\/2736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/media\/2733"}],"wp:attachment":[{"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/media?parent=2735"}],"wp:term":[{"taxonomy":"kategorie","embeddable":true,"href":"https:\/\/www.zabler.de\/en\/wp-json\/wp\/v2\/kategorie?post=2735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}